{"id":17630,"date":"2022-01-11T11:11:11","date_gmt":"2022-01-11T11:11:11","guid":{"rendered":"https:\/\/losencajeros.es\/producto\/servilletas-de-cocktail-bilbao-reseda\/"},"modified":"2024-06-19T10:23:41","modified_gmt":"2024-06-19T10:23:41","slug":"set-of-four-bilbao-reseda-linen-cocktail-napkins","status":"publish","type":"product","link":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/","title":{"rendered":"set of four bilbao reseda linen cocktail napkins"},"content":{"rendered":"<p>Each cocktail napkin is woven from natural linen and accented with embroidered scalloped trim.<\/p>\n<p>Made in Spain.<\/p>\n<p>Measurement: 15 x 20 cm \/ 6&#8243; x 8&#8243;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Set of four embroidered linen cocktail napkins.<\/p>\n","protected":false},"featured_media":29695,"template":"","meta":{"_acf_changed":false},"product_cat":[1659,1763],"product_tag":[5546,1868,2515,5547,5548,2714,5549,5550,5551,3450,5552,5553,5554,2193,2225,5555,5556,5557],"giftcard-category":[],"class_list":{"0":"post-17630","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-final-sale","7":"product_cat-cocktail-napkins","8":"product_tag-accesorios-mesa-lino-en","9":"product_tag-bilbao-en","10":"product_tag-pack-servilletas-lino-en","11":"product_tag-servilletas-cocktail-carrara-white-en","12":"product_tag-servilletas-cocktail-de-lino-hechas-a-mano-en","13":"product_tag-servilletas-cocktail-lino-en","14":"product_tag-servilletas-cocktail-lino-artesanales-en","15":"product_tag-servilletas-cocktail-lino-elegantes-en","16":"product_tag-servilletas-cocktail-lino-lujo-en","17":"product_tag-servilletas-cocktail-lino-tokyo-green-en","18":"product_tag-servilletas-cocktail-para-aperitivos-en","19":"product_tag-servilletas-cocktail-sostenibles-en","20":"product_tag-servilletas-coctel-lino-en","21":"product_tag-servilletas-de-cocktail-en","22":"product_tag-servilletas-de-cocktail-bilbao-reseda-en","23":"product_tag-servilletas-lino-pequenas-en","24":"product_tag-servilletas-lino-tokyo-green-en","25":"product_tag-servilletas-lino-verdes-en","27":"first","28":"onbackorder","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>set of four bilbao reseda linen cocktail napkins | Los Encajeros<\/title>\n<meta name=\"description\" content=\"Set of four embroidered linen cocktail napkins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"set of four bilbao reseda linen cocktail napkins | Los Encajeros\" \/>\n<meta property=\"og:description\" content=\"Set of four embroidered linen cocktail napkins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/\" \/>\n<meta property=\"og:site_name\" content=\"Los Encajeros\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T10:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/BEA9327-PACK-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1709\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"set of four bilbao reseda linen cocktail napkins | Los Encajeros","description":"Set of four embroidered linen cocktail napkins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/","og_locale":"en_US","og_type":"article","og_title":"set of four bilbao reseda linen cocktail napkins | Los Encajeros","og_description":"Set of four embroidered linen cocktail napkins.","og_url":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/","og_site_name":"Los Encajeros","article_modified_time":"2024-06-19T10:23:41+00:00","og_image":[{"width":1709,"height":2560,"url":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/BEA9327-PACK-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/","url":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/","name":"set of four bilbao reseda linen cocktail napkins | Los Encajeros","isPartOf":{"@id":"https:\/\/losencajeros.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/#primaryimage"},"image":{"@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/#primaryimage"},"thumbnailUrl":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/BEA9327-PACK-1-scaled.jpg","datePublished":"2022-01-11T11:11:11+00:00","dateModified":"2024-06-19T10:23:41+00:00","description":"Set of four embroidered linen cocktail napkins.","breadcrumb":{"@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/#primaryimage","url":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/BEA9327-PACK-1-scaled.jpg","contentUrl":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/BEA9327-PACK-1-scaled.jpg","width":1709,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/losencajeros.es\/en\/product\/set-of-four-bilbao-reseda-linen-cocktail-napkins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/losencajeros.es\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/losencajeros.es\/shop\/"},{"@type":"ListItem","position":3,"name":"set of four bilbao reseda linen cocktail napkins"}]},{"@type":"WebSite","@id":"https:\/\/losencajeros.es\/#website","url":"https:\/\/losencajeros.es\/","name":"Los Encajeros","description":"Referente de elegancia y buen gusto a la hora de dise\u00f1ar y confeccionar ropa de mesa y cama","publisher":{"@id":"https:\/\/losencajeros.es\/#organization"},"alternateName":"Los Encajeros Bilbao","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/losencajeros.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/losencajeros.es\/#organization","name":"Los Encajeros","url":"https:\/\/losencajeros.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/losencajeros.es\/#\/schema\/logo\/image\/","url":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/Logo-Encajeros-2026.png","contentUrl":"https:\/\/losencajeros.es\/wp-content\/uploads\/2022\/01\/Logo-Encajeros-2026.png","width":6245,"height":2188,"caption":"Los Encajeros"},"image":{"@id":"https:\/\/losencajeros.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/product\/17630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/product\/17630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/media\/29695"}],"wp:attachment":[{"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/media?parent=17630"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/product_cat?post=17630"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/product_tag?post=17630"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/losencajeros.es\/en\/wp-json\/wp\/v2\/giftcard-category?post=17630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}